{"id":2,"date":"2022-11-09T20:00:52","date_gmt":"2022-11-09T20:00:52","guid":{"rendered":"https:\/\/hello.uniurb.it\/?page_id=2"},"modified":"2026-06-24T11:54:55","modified_gmt":"2026-06-24T11:54:55","slug":"benvenuti","status":"publish","type":"page","link":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/","title":{"rendered":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#5e5e5e&#8221; background_image=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2026\/06\/smart-162.jpeg&#8221; background_blend=&#8221;soft-light&#8221; height=&#8221;430px&#8221; height_tablet=&#8221;350px&#8221; height_phone=&#8221;260px&#8221; height_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat|700||on|||||&#8221; text_font_size=&#8221;1.3em&#8221; text_line_height=&#8221;1.2em&#8221; custom_margin=&#8221;||3px|||&#8221; text_font_size_tablet=&#8221;1.2em&#8221; text_font_size_phone=&#8221;1.1em&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Campus Scientifico Enrico Mattei<\/h1>\n<h3>Intervento di prevenzione sismica ed efficientamento energetico<\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#005092&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;39px|||||&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p style=\"font-weight: 400;\"><strong>24 giugno 2026 \u2014 POC 2014-2020 Marche &#8211; DGR n.240 del 09\/03\/2026 &#8211; Intervento Campus E. Mattei<\/strong><\/p>\n<div><\/div>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">A seguito della <strong>completa realizzazione ed entrata in funzione<\/strong> dell\u2019intervento in oggetto e della modifica del 06\/05\/2026 alla Convenzione stipulata in data 9 maggio 2019, registro int. 2019\/408, fra Regione Marche e Universit\u00e0 degli Studi di Urbino Carlo Bo per l\u2019attuazione di interventi di efficientamento energetico e di prevenzione sismica edifici pubblici. POR FESR 2014-2020 Asse 8 \u2013 Int. 25.1.1 e 28.1.1 e Programma Operativo Complementare (POC) 2014-2020 di cui alla DGR n.204 del 09\/03\/2026<\/p>\n<p style=\"font-weight: 400;\">Sono stati stabiliti i rispettivi obblighi e regolate le modalit\u00e0 di erogazione delle risorse connesse alla realizzazione dell\u2019intervento proposto dall\u2019Universit\u00e0 degli Studi di Urbino Carlo Bo, di cui alla Deliberazione di Giunta Regionale del 4 marzo 2019, n. 239, denominato \u201cCampus scientifico E. Mattei\u201d secondo lo stanziamento POR FESR 2014-2020 pari a \u20ac 2.750.000,00 per la scheda di attuazione 25.1.1 (efficienza energetica) e pari a \u20ac 2.750.000,00 per la scheda di attuazione 28.1.1 (adeguamento o miglioramento sismico), di cui <strong>\u20ac 275.000,00<\/strong> coperti dal POC Marche 2014-2020, azione 8.8 e azione 8.9, ai sensi della DGR n. 204\/2026\u201d.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#8F8F8F&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;256573,256576,256575,256572&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; min_height=&#8221;198.6px&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#474747&#8243; text_font_size=&#8221;1.3em&#8221; text_line_height=&#8221;1.2em&#8221; header_text_color=&#8221;#474747&#8243; text_font_size_tablet=&#8221;1.2em&#8221; text_font_size_phone=&#8221;1.1em&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>L&#8217;intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei ha l&#8217;obiettivo di <strong>migliorare la funzionalit\u00e0, la tecnologia e gli impianti dell&#8217;edificio<\/strong>, <strong>aumentare l&#8217;efficienza energetica<\/strong> e <strong>adeguare sismicamente la struttura<\/strong>.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font=&#8221;Montserrat||||||||&#8221; text_text_color=&#8221;#474747&#8243; text_font_size=&#8221;1.3em&#8221; text_line_height=&#8221;1.2em&#8221; header_text_color=&#8221;#474747&#8243; text_font_size_tablet=&#8221;1.2em&#8221; text_font_size_phone=&#8221;1.1em&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>Le azioni previste includono il consolidamento strutturale e l&#8217;adeguamento sismico, l&#8217;efficientamento energetico, la conformit\u00e0 antincendio, la rimozione di barriere architettoniche, l&#8217;aggiunta di servizi igienici accessibili, la riorganizzazione degli spazi interni, la compartimentazione dei vari settori, l&#8217;aggiornamento delle finiture, l&#8217;innovazione tecnica, l&#8217;aggiunta di arredi tecnici, la valorizzazione degli spazi esterni e la sostenibilit\u00e0 ambientale.\u00a0<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;256424,256425,256426,256427,256428,256429,256430,256431,256432,256433,256434,256435,256436,256437,256438,256439,256440,256441,256442,256443,256444,256445,256446,256447,256448,256449,256450,256451,256452,256453,256454,256455,256456,256457,256458,256459,256460,256461,256462&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 class=\"page\" title=\"Page 2\"><span>Azioni previste dal progetto:<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul>\n<li><span>consolidamento strutturale e adeguamento antisismico;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>efficientamento energetico tramite il rifacimento integrale degli impianti meccanici, elettrici e speciali e la coibentazione dell&#8217;<\/span><span><\/span><span>involucro tramite la realizzazione di un cappotto termico, la sostituzione dei serramenti, il rifacimento della copertura e l&#8217;<\/span><span><\/span><span>isolamento dei solai controterra;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>conformita\u0300 antincendio;<\/span><span><\/span><\/li>\n<li><span>abbattimento delle barriere architettoniche grazie alla realizzazione di tre nuovi ascensori e all&#8217;<\/span><span><\/span><span>inserimento di nuove rampe interne e di raccordo con gli spazi di relazione esterni;<\/span><\/li>\n<li><span>aumento dei blocchi dei servizi igienici, da due a quattro, ciascuno dotato di un locale riservato ai diversamente abili;<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; custom_padding=&#8221;|||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><span>rifunzionalizzazione degli spazi interni in coerenza al quadro esigenziale novato;<\/span><\/li>\n<li><span>compartimentazione dei vari settori grazie a sistemi per il controllo degli accessi;<\/span><\/li>\n<li><span>inserimento di finiture idonee e rispondenti alle normative vigenti (partizioni interne, serramenti interni, controsoffitti, pavimenti, rivestimenti murari);<\/span><\/li>\n<li><span>innovazione tecnica delle soluzioni architettoniche, strutturali e impiantistiche di progetto;<\/span><\/li>\n<li><span>inserimento di arredi tecnici e non;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>valorizzazione degli spazi esterni esistenti;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>sostenibilita\u0300 ambientale delle scelte adottate.<br \/><\/span><span><\/span><span><\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_divider color=&#8221;#6B6B6B&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;RGBA(255,255,255,0)&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3>Progetto realizzato grazie a <strong>POR MARCHE &#8211; FESR 2014-2020<\/strong>\u00a0<strong><a href=\"https:\/\/www.regione.marche.it\/Portals\/0\/Europa_Estero\/Fondi%20europei\/FESR%2014-20\/Reg.1301-2013.pdf?ver=2016-06-06-100028-450\">Fondo Europeo di Sviluppo Regionale:<\/a><\/strong><\/h3>\n<h3><span style=\"font-size: 14px; color: #666666;\"><\/span><\/h3>\n<h3><span style=\"font-size: 14px; color: #666666;\"><strong>ASSE 8 &#8211; AZIONE 25.1.1<\/strong> &#8211; Interventi di efficienza energetica negli edifici pubblici &#8211; Edilizia Universitaria \u2014 Euro 2.750.000.<br \/><\/span><span style=\"font-size: 14px; color: #666666;\"><strong>ASSE 8 &#8211; AZIONE 28.1.1<\/strong> &#8211; Interventi di natura strutturale o opere strettamente connesse, di adeguamento o miglioramento sismico &#8211; Edilizia Universitaria \u2014\u00a0<\/span><span style=\"font-size: 14px; color: #666666;\">Euro 2.750.000.<\/span><\/h3>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei_Tavola-disegno-1.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei_Tavola disegno 1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-02.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-02&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-03.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-03&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-04.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-04&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#6B6B6B&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;15px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><strong>Adeguamento\u00a0sismico<\/strong><\/h3>\n<p>L&#8217;intervento prevede l&#8217;adeguamento sismico dei tre blocchi dell&#8217;edificio, che contempla il consolidamento del piano fondale, la realizzazione di elementi sismo-resistenti in acciaio, la realizzazione di adeguati giunti sismici tra i blocchi, il collegamento delle parti dell&#8217;edificio mediante una reticolare piana e la realizzazione di cuciture e imperniature armate.<\/p>\n<p>L&#8217;obiettivo \u00e8 quello di <strong>adeguare la struttura alle vigenti normative sismiche<\/strong>, minimizzando l&#8217;impatto degli interventi sull&#8217;aspetto esterno dell&#8217;edificio.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_gallery gallery_ids=&#8221;256470,256463,256471,256480,256465,256464,256479,256466,256467,256468,256469,256472,256473,256474,256475,256476,256477,256478,256481,256482,256483,256484,256485,256486,256487,256488,256489,256490,256491,256492,256493,256494,256495,256496&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8221;1_2,1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3 class=\"page\" title=\"Page 2\"><span>Azioni previste:<\/span><\/h3>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;|||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<div class=\"page\" title=\"Page 2\">\n<div class=\"section\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<ul>\n<li><span><\/span><span>consolidamento del piano fondale per ottenere una migliore ripartizione dei carichi sul terreno, mediante la realizzazione di getto in calcestruzzo armato in grado di collegare i plinti esistenti;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>realizzazione di elementi sismo-resistenti in acciaio (montanti HEB200, diagonali UPN200, in pianta dim. 20&#215;120 cm), come irrigidimento della struttura, a contrasto delle sollecitazioni dinamiche dovute ad eventi tellurici, con intensita\u0300 prevista dalla normativa;<\/span><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;|||10px|false|false&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<ul>\n<li style=\"list-style-type: none;\">\n<ul>\n<li><span>realizzazione di adeguati giunti sismici tra i blocchi 1 e 2 e tra i blocchi 2 e 3;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>collegamento delle due parti di edificio che costituiscono il blocco 1 e il blocco 3, mediante una rete di armatura\u00a0biassiale bilanciata, atta a sostenere i carichi, come copertura;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>nel blocco 2 si prevede di rendere collaboranti i pilastri in cemento armato annegati nella muratura con le limitrofe colonne in acciaio;<br \/><\/span><span><\/span><span><\/span><\/li>\n<li><span>realizzazione di cuciture e imperniature armate per rendere monolitici alcuni elementi presenti (ad esempio gli elementi prefabbricati del blocco 3).<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#FFFFFF&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_text _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; text_font_size_tablet=&#8221;18px&#8221; text_font_size_phone=&#8221;15px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><strong>Efficientamento energetico<\/strong><\/h3>\n<p>L&#8217;intervento prevede il miglioramento energetico, che contempla interventi mirati all&#8217;involucro edilizio, compresi il rifacimento dei solai controterra, la realizzazione di un cappotto esterno per le murature perimetrali, la sostituzione dei serramenti, il rifacimento della copertura e la coibentazione dei solai controterra e interventi mirati all&#8217;efficientamento degli impianti compresi la demolizione degli impianti esistenti e\u00a0l&#8217;installazione di impianti pi\u00f9 efficienti, come le centrali tecnologiche, l&#8217;impianto di condizionamento e riscaldamento, l&#8217;impianto di rinnovo dell&#8217;aria, l&#8217;impianto di estrazione dai laboratori, l&#8217;impianto idrico sanitario e fogna, l&#8217;impianto idrico antincendio e l&#8217;impianto di distribuzione gas tecnici.<\/p>\n<p>L&#8217;obiettivo finale \u00e8 la <strong>riduzione dell&#8217;impatto energetico<\/strong> dell&#8217;edificio.<\/p>\n<p>[\/et_pb_text][et_pb_gallery gallery_ids=&#8221;256510,256503,256509,256511,256504,256500,256506,256499,256502,256507,256505,256508&#8243; show_title_and_caption=&#8221;off&#8221; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; fullwidth=&#8221;on&#8221; _builder_version=&#8221;4.27.6&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#5e5e5e&#8221; background_image=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2026\/06\/smart-163.jpeg&#8221; background_blend=&#8221;soft-light&#8221; height=&#8221;430px&#8221; height_tablet=&#8221;350px&#8221; height_phone=&#8221;260px&#8221; height_last_edited=&#8221;on|phone&#8221; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; title_text=&#8221;Campus Scientifico Enrico Mattei &#8211; Aula Magna&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#D6D6D6&#8243; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_4,1_4,1_4,1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei_Tavola-disegno-1.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei_Tavola disegno 1&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-02.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-02&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-03.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-03&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][et_pb_column type=&#8221;1_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_image src=&#8221;https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/loghi-campus-scientifico-enrico-mattei-04.png&#8221; title_text=&#8221;loghi-campus-scientifico-enrico-mattei-04&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei: riqualificazione strutturale, innovazione impiantistica e miglioramento della sostenibilit\u00e0 e accessibilit\u00e0 degli spazi universitari.<\/p>\n","protected":false},"author":1,"featured_media":256575,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:paragraph -->\r\n<p>This is an example page. It's different from a blog post because it will stay in one place and will show up in your site navigation (in most themes). Most people start with an About page that introduces them to potential site visitors. It might say something like this:<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:quote -->\r\n<blockquote class=\"wp-block-quote\"><p>Hi there! I'm a bike messenger by day, aspiring actor by night, and this is my website. I live in Los Angeles, have a great dog named Jack, and I like pi\u00f1a coladas. (And gettin' caught in the rain.)<\/p><\/blockquote>\r\n<!-- \/wp:quote -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>...or something like this:<\/p>\r\n<!-- \/wp:paragraph -->\r\n\r\n<!-- wp:quote -->\r\n<blockquote class=\"wp-block-quote\"><p>The XYZ Doohickey Company was founded in 1971, and has been providing quality doohickeys to the public ever since. Located in Gotham City, XYZ employs over 2,000 people and does all kinds of awesome things for the Gotham community.<\/p><\/blockquote>\r\n<!-- \/wp:quote -->\r\n\r\n<!-- wp:paragraph -->\r\n<p>As a new WordPress user, you should go to <a href=\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-admin\/\">your dashboard<\/a> to delete this page and create new pages for your content. Have fun!<\/p>\r\n<!-- \/wp:paragraph -->","_et_gb_content_width":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.12 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Benvenuti nel nuovo Campus Scientifico Enrico Mattei - Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo<\/title>\n<meta name=\"description\" content=\"L\u2019incontro con le studentesse e gli studenti delle Scuole secondarie di secondo grado costituisce da venti anni uno degli appuntamenti pi\u00f9 qualificanti dell\u2019Universit\u00e0 degli Studi di Urbino Carlo Bo. Universit\u00e0 Aperta \u00e8 infatti il momento in cui l\u2019Ateneo \u00e8 chiamato a presentare la propria offerta formativa collaborando all\u2019orientamento alla scelta degli studi universitari.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Benvenuti nel nuovo Campus Scientifico Enrico Mattei\" \/>\n<meta property=\"og:description\" content=\"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei: riqualificazione strutturale, innovazione impiantistica e miglioramento della sostenibilit\u00e0 e accessibilit\u00e0 degli spazi universitari.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-24T11:54:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/campus-mattei.003.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Benvenuti nel nuovo Campus Scientifico Enrico Mattei\" \/>\n<meta name=\"twitter:description\" content=\"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei: riqualificazione strutturale, innovazione impiantistica e miglioramento della sostenibilit\u00e0 e accessibilit\u00e0 degli spazi universitari.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/campus-mattei.002.jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\",\"url\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\",\"name\":\"Benvenuti nel nuovo Campus Scientifico Enrico Mattei - Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo\",\"isPartOf\":{\"@id\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#website\"},\"datePublished\":\"2022-11-09T20:00:52+00:00\",\"dateModified\":\"2026-06-24T11:54:55+00:00\",\"description\":\"L\u2019incontro con le studentesse e gli studenti delle Scuole secondarie di secondo grado costituisce da venti anni uno degli appuntamenti pi\u00f9 qualificanti dell\u2019Universit\u00e0 degli Studi di Urbino Carlo Bo. Universit\u00e0 Aperta \u00e8 infatti il momento in cui l\u2019Ateneo \u00e8 chiamato a presentare la propria offerta formativa collaborando all\u2019orientamento alla scelta degli studi universitari.\",\"breadcrumb\":{\"@id\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Benvenuti nel nuovo Campus Scientifico Enrico Mattei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#website\",\"url\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/\",\"name\":\"Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo\",\"description\":\"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei - Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo","description":"L\u2019incontro con le studentesse e gli studenti delle Scuole secondarie di secondo grado costituisce da venti anni uno degli appuntamenti pi\u00f9 qualificanti dell\u2019Universit\u00e0 degli Studi di Urbino Carlo Bo. Universit\u00e0 Aperta \u00e8 infatti il momento in cui l\u2019Ateneo \u00e8 chiamato a presentare la propria offerta formativa collaborando all\u2019orientamento alla scelta degli studi universitari.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei","og_description":"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei: riqualificazione strutturale, innovazione impiantistica e miglioramento della sostenibilit\u00e0 e accessibilit\u00e0 degli spazi universitari.","og_url":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/","og_site_name":"Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo","article_modified_time":"2026-06-24T11:54:55+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/campus-mattei.003.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei","twitter_description":"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei: riqualificazione strutturale, innovazione impiantistica e miglioramento della sostenibilit\u00e0 e accessibilit\u00e0 degli spazi universitari.","twitter_image":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-content\/uploads\/2023\/02\/campus-mattei.002.jpeg","twitter_misc":{"Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/","url":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/","name":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei - Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo","isPartOf":{"@id":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#website"},"datePublished":"2022-11-09T20:00:52+00:00","dateModified":"2026-06-24T11:54:55+00:00","description":"L\u2019incontro con le studentesse e gli studenti delle Scuole secondarie di secondo grado costituisce da venti anni uno degli appuntamenti pi\u00f9 qualificanti dell\u2019Universit\u00e0 degli Studi di Urbino Carlo Bo. Universit\u00e0 Aperta \u00e8 infatti il momento in cui l\u2019Ateneo \u00e8 chiamato a presentare la propria offerta formativa collaborando all\u2019orientamento alla scelta degli studi universitari.","breadcrumb":{"@id":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/project.uniurb.it\/campus-scientifico-mattei\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/"},{"@type":"ListItem","position":2,"name":"Benvenuti nel nuovo Campus Scientifico Enrico Mattei"}]},{"@type":"WebSite","@id":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/#website","url":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/","name":"Campus Scientifico Enrico Mattei \u2014 Universit\u00e0 degli Studi di Urbino Carlo Bo","description":"Intervento di prevenzione sismica ed efficientamento energetico del Campus Scientifico Enrico Mattei","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/pages\/2"}],"collection":[{"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/comments?post=2"}],"version-history":[{"count":294,"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/pages\/2\/revisions"}],"predecessor-version":[{"id":256610,"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/pages\/2\/revisions\/256610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/media\/256575"}],"wp:attachment":[{"href":"https:\/\/project.uniurb.it\/campus-scientifico-mattei\/wp-json\/wp\/v2\/media?parent=2"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}